{"id":3231,"date":"2024-03-14T15:56:12","date_gmt":"2024-03-14T20:56:12","guid":{"rendered":"https:\/\/gigacon.com.co\/web\/?p=3231"},"modified":"2024-03-14T15:56:12","modified_gmt":"2024-03-14T20:56:12","slug":"desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril","status":"publish","type":"post","link":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/","title":{"rendered":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:var(--awb-color3);border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center\" style=\"max-width:calc( 1200px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-animated\" data-animationType=\"fadeIn\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"text-align:center;font-size:var(--awb-typography2-font-size);line-height:var(--awb-typography2-line-height);letter-spacing:var(--awb-typography2-letter-spacing);text-transform:var(--awb-typography2-text-transform);font-family:var(--awb-typography2-font-family);font-weight:var(--awb-typography2-font-weight);font-style:var(--awb-typography2-font-style);margin-bottom:10px;\"><p>Desmontaje de las Torres Gr\u00faas<\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1366px) {.fusion-title.fusion-title-1{margin-top:10px!important; margin-right:0px!important;margin-bottom:30px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:10px!important; margin-right:0px!important;margin-bottom:30px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"margin-top:10px;margin-right:0px;margin-bottom:30px;margin-left:0px;\"><h2 class=\"title-heading-center\" style=\"margin:0;letter-spacing:-1px;\">Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril.<\/h2><\/div><div class=\"fusion-text fusion-text-2 fusion-text-no-margin\" style=\"text-align:center;margin-right:10%;margin-left:10%;\"><p>El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final con el exitoso desmontaje de las dos imponentes torres gr\u00faas de alta capacidad COMANSA CM 335. Estas majestuosas estructuras, provenientes de la factor\u00eda de Comansa en Hangzhou, China, fueron pieza clave en la realizaci\u00f3n de este colosal proyecto. En este art\u00edculo, te sumergimos en el fascinante proceso de desmontaje de las gr\u00faas y exploramos el significado trascendental que el nuevo puente representa para el pa\u00eds.<\/p>\n<p>GIGACON, el representante exclusivo de COMANSA en Colombia, enfrent\u00f3 el desaf\u00edo de retirar las dos torres de acero, meticulosamente planificando cada paso de la maniobra. Esto fue posible gracias a que la empresa suministr\u00f3 las gr\u00faas y les proporcion\u00f3 mantenimiento durante todo el trabajo realizado en el puente.<\/p>\n<p>Su equipo t\u00e9cnico, tras varias visitas al sitio, utiliz\u00f3 el software 3dlift para simular el proceso. Como resultado, se opt\u00f3 por una moderna gr\u00faa m\u00f3vil de 60 metros de pluma, cuidadosamente seleccionada para evitar da\u00f1os al tablero del puente, junto con el contrapeso adecuado. El software calcul\u00f3 las cargas con precisi\u00f3n, las cuales fueron aprobadas por el dise\u00f1ador del puente. Mientras tanto, en la planta de GIGACON, operarios y t\u00e9cnicos se preparaban con las herramientas y equipos necesarios para el trabajo.<\/p>\n<p>El momento crucial llega con la partida desde la planta principal de GIGACON en Cota. Equipos clave, incluyendo la gr\u00faa principal GMK 5130 \u2013 2 y la gr\u00faa auxiliar Kenworth T900, junto con tractocamiones y un cami\u00f3n tipo 600, inician su viaje en caravana. Tras recorrer sin contratiempos los 110 kil\u00f3metros hasta el lugar de la operaci\u00f3n, su misi\u00f3n es clara: desmontar los dos gigantes de acero y depositarlos en el patio de la concesi\u00f3n Coviandes, cerca de Villavicencio. Acompa\u00f1ando a los equipos, un experimentado grupo de m\u00e1s de 15 personas, con diversas especialidades, se enfrenta al reto de llevar a cabo la misi\u00f3n sin contratiempos.<\/p>\n<p>En el campo de acci\u00f3n, un experimentado operador de gr\u00faa m\u00f3vil ejecuta los izajes siguiendo las instrucciones de los t\u00e9cnicos de desmontaje, quienes desde las torres gr\u00faas a 70 metros de altura gu\u00edan los movimientos por radio con la precisi\u00f3n de un cirujano. Los desmontajes se completan en un tiempo r\u00e9cord de 15 d\u00edas de trabajo intenso, marcados por la camarader\u00eda y el intercambio de conocimientos entre operarios, aparejadores, conductores, t\u00e9cnicos y personal SST en el c\u00e1lido municipio de Guayabetal. GIGACON ha cumplido su labor con excelencia, acercando al puente Chirajara un paso m\u00e1s hacia su entrada en servicio, beneficiando a todos los colombianos que transitan por la v\u00eda al llano.<\/p>\n<p>El puente Chirajara, con una longitud de 412 metros, es parte del ambicioso proyecto vial de la doble calzada Bogot\u00e1-Villavicencio, destinado a mejorar la movilidad y seguridad de los usuarios en esta vital ruta. Adem\u00e1s, representa un s\u00edmbolo de resiliencia, reemplazando al puente que colaps\u00f3 tr\u00e1gicamente en 2018, cobrando la vida de nueve trabajadores. Con su construcci\u00f3n, se rinde homenaje a las v\u00edctimas y se reafirma el compromiso tanto de las empresas como del gobierno con el desarrollo del pa\u00eds.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 80px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 0px;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 0px;}@media only screen and (max-width:1366px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;margin-bottom : 70px;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;margin-bottom : 50px;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 50px 0px 0px 0px;\"><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:40px;width:100%;max-width:90%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"border-color:var(--awb-color4);border-top-width:2px;\"><\/div><\/div><style type=\"text\/css\">@media only screen and (max-width:1366px) {.fusion-title.fusion-title-2{margin-top:10px!important; margin-right:0px!important;margin-bottom:30px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-2{margin-top:10px!important; margin-right:0px!important;margin-bottom:30px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"margin-top:10px;margin-right:0px;margin-bottom:30px;margin-left:0px;\"><h3 class=\"title-heading-center\" style=\"margin:0;letter-spacing:-1px;\">\u00bfQu\u00e9 Opinas del Puente Chirajara?<\/h3><\/div><div class=\"fusion-text fusion-text-3 fusion-text-no-margin\" style=\"text-align:justify;margin-right:10%;margin-left:10%;\"><p>\u00bfConsideras que mejorar\u00e1 significativamente la conexi\u00f3n entre Bogot\u00e1 y los Llanos Orientales? \u00a1D\u00e9janos tu opini\u00f3n en los comentarios o comparte este art\u00edculo con tus amigos para iniciar la conversaci\u00f3n sobre este importante hito ingenieril en Colombia!<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:10px;width:100%;max-width:90%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"border-color:var(--awb-color4);border-top-width:2px;\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 50px !important;padding-right : 0px !important;margin-right : 0px;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 0px;}@media only screen and (max-width:1366px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 100px !important;margin-right : 0px;margin-left : 0px;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el vertiginoso mundo de la construcci\u00f3n, las torres gr\u00faas desempe\u00f1an un papel crucial al elevar y mover pesadas cargas, agilizando los procesos y optimizando la productividad en el sitio. Dominar la operaci\u00f3n de estas poderosas herramientas es esencial&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,27],"tags":[30,40,39,34],"class_list":["post-3231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-gremio-construccion","category-novedades-gigacon","tag-construccion","tag-infraestructura-en-colombia","tag-mejores-practicas-uso-de-torregruas","tag-torre-gruas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS<\/title>\n<meta name=\"description\" content=\"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS\" \/>\n<meta property=\"og:description\" content=\"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\" \/>\n<meta property=\"og:site_name\" content=\"GIGACON GR\u00daAS\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-14T20:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dmcolwebmasgig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dmcolwebmasgig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\"},\"author\":{\"name\":\"dmcolwebmasgig\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/4670772230fab4790502e8b4c4d61c1f\"},\"headline\":\"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril\",\"datePublished\":\"2024-03-14T20:56:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\"},\"wordCount\":1864,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg\",\"keywords\":[\"construcci\u00f3n\",\"Infraestructura en Colombia\",\"Mejores practicas uso de torregr\u00faas\",\"torre gr\u00faas\"],\"articleSection\":[\"Noticias Gremio Construcci\u00f3n\",\"Novedades Gigacon\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\",\"url\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\",\"name\":\"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS\",\"isPartOf\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg\",\"datePublished\":\"2024-03-14T20:56:12+00:00\",\"description\":\"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...\",\"breadcrumb\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage\",\"url\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg\",\"contentUrl\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg\",\"width\":1500,\"height\":794,\"caption\":\"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/gigacon.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#website\",\"url\":\"https:\/\/gigacon.com.co\/web\/\",\"name\":\"GIGACON GR\u00daAS\",\"description\":\"Alquiler y venta de torregr\u00faas -telesc\u00f3picas - comansa para todo proyecto.\",\"publisher\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/#organization\"},\"alternateName\":\"GIGACON GR\u00daAS & GIGACON TRANSPORTES\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gigacon.com.co\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#organization\",\"name\":\"GIGACON GR\u00daAS\",\"alternateName\":\"GIGACON GR\u00daAS & TRANSPORTES\",\"url\":\"https:\/\/gigacon.com.co\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2023\/03\/gigacon-favicon-ipad-152x152-1.png\",\"contentUrl\":\"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2023\/03\/gigacon-favicon-ipad-152x152-1.png\",\"width\":152,\"height\":152,\"caption\":\"GIGACON GR\u00daAS\"},\"image\":{\"@id\":\"https:\/\/gigacon.com.co\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/gigacongruas\/\",\"https:\/\/www.youtube.com\/user\/gigaconltda\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/4670772230fab4790502e8b4c4d61c1f\",\"name\":\"dmcolwebmasgig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31a545ead308cb764775b102d0021d5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31a545ead308cb764775b102d0021d5c?s=96&d=mm&r=g\",\"caption\":\"dmcolwebmasgig\"},\"sameAs\":[\"https:\/\/gigacon.com.co\/web\"],\"url\":\"https:\/\/gigacon.com.co\/web\/author\/dmcolwebmasgig\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS","description":"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/","og_locale":"es_ES","og_type":"article","og_title":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS","og_description":"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...","og_url":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/","og_site_name":"GIGACON GR\u00daAS","article_published_time":"2024-03-14T20:56:12+00:00","og_image":[{"width":1500,"height":794,"url":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg","type":"image\/jpeg"}],"author":"dmcolwebmasgig","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"dmcolwebmasgig","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#article","isPartOf":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/"},"author":{"name":"dmcolwebmasgig","@id":"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/4670772230fab4790502e8b4c4d61c1f"},"headline":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril","datePublished":"2024-03-14T20:56:12+00:00","mainEntityOfPage":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/"},"wordCount":1864,"commentCount":1,"publisher":{"@id":"https:\/\/gigacon.com.co\/web\/#organization"},"image":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage"},"thumbnailUrl":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg","keywords":["construcci\u00f3n","Infraestructura en Colombia","Mejores practicas uso de torregr\u00faas","torre gr\u00faas"],"articleSection":["Noticias Gremio Construcci\u00f3n","Novedades Gigacon"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/","url":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/","name":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril | GIGACON GR\u00daAS","isPartOf":{"@id":"https:\/\/gigacon.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage"},"image":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage"},"thumbnailUrl":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg","datePublished":"2024-03-14T20:56:12+00:00","description":"El nuevo puente Chirajara, una monumental obra de ingenier\u00eda que enlaza Bogot\u00e1 con los Llanos Orientales se acerca a su fase final...","breadcrumb":{"@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#primaryimage","url":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg","contentUrl":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2024\/03\/puente-chirajara-web.jpg","width":1500,"height":794,"caption":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril"},{"@type":"BreadcrumbList","@id":"https:\/\/gigacon.com.co\/web\/desmontaje-de-las-torres-gruas-en-el-nuevo-puente-chirajara-un-hito-ingenieril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gigacon.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Desmontaje de las Torres Gr\u00faas en el Nuevo Puente Chirajara: Un Hit\u00f3 Ingenieril"}]},{"@type":"WebSite","@id":"https:\/\/gigacon.com.co\/web\/#website","url":"https:\/\/gigacon.com.co\/web\/","name":"GIGACON GR\u00daAS","description":"Alquiler y venta de torregr\u00faas -telesc\u00f3picas - comansa para todo proyecto.","publisher":{"@id":"https:\/\/gigacon.com.co\/web\/#organization"},"alternateName":"GIGACON GR\u00daAS & GIGACON TRANSPORTES","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gigacon.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/gigacon.com.co\/web\/#organization","name":"GIGACON GR\u00daAS","alternateName":"GIGACON GR\u00daAS & TRANSPORTES","url":"https:\/\/gigacon.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/gigacon.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2023\/03\/gigacon-favicon-ipad-152x152-1.png","contentUrl":"https:\/\/gigacon.com.co\/web\/wp-content\/uploads\/2023\/03\/gigacon-favicon-ipad-152x152-1.png","width":152,"height":152,"caption":"GIGACON GR\u00daAS"},"image":{"@id":"https:\/\/gigacon.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/gigacongruas\/","https:\/\/www.youtube.com\/user\/gigaconltda"]},{"@type":"Person","@id":"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/4670772230fab4790502e8b4c4d61c1f","name":"dmcolwebmasgig","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/gigacon.com.co\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31a545ead308cb764775b102d0021d5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31a545ead308cb764775b102d0021d5c?s=96&d=mm&r=g","caption":"dmcolwebmasgig"},"sameAs":["https:\/\/gigacon.com.co\/web"],"url":"https:\/\/gigacon.com.co\/web\/author\/dmcolwebmasgig\/"}]}},"_links":{"self":[{"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/posts\/3231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/comments?post=3231"}],"version-history":[{"count":0,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/posts\/3231\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/media\/3232"}],"wp:attachment":[{"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/media?parent=3231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/categories?post=3231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gigacon.com.co\/web\/wp-json\/wp\/v2\/tags?post=3231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}